{"id":336,"date":"2008-07-02T17:26:34","date_gmt":"2008-07-02T15:26:34","guid":{"rendered":"http:\/\/www.uwe-tippmann.de\/blog\/2008\/07\/02\/google-offline-geht-online\/"},"modified":"2008-07-03T08:41:22","modified_gmt":"2008-07-03T06:41:22","slug":"google-offline-geht-online","status":"publish","type":"post","link":"https:\/\/www.uwe-tippmann.de\/blog\/2008\/07\/02\/google-offline-geht-online\/","title":{"rendered":"Google offline geht online"},"content":{"rendered":"<p>Google engagiert sich seit geraumer Zeit auch in der Durchf&uuml;hrung von klassischen Media-Kampagnen. Dabei werden Kan&auml;le wie TV, Radio und klassische Printmedien ins Boot genommen. Jetzt hat sich diese noch recht neue Abteilung dazu entschlossen einen <a href=\"http:\/\/google-tmads.blogspot.com\/2008\/06\/google-offline-goes-online.html\" target=\"_blank\">offiziellen Blog<\/a> zu starten. Derartige offene Schnittstellen nach Au&szlig;en sind bei Google keine Seltenheit und schaffen es im besten Fall auch in die <a href=\"http:\/\/technorati.com\/pop\/blogs\/?page=2\" target=\"_blank\">Top 20 der Technorati Charts<\/a>. Das Corporate Blogging ist eine beliebte PR-Strategie und wird von den Nutzern oft gut angenommen.<\/p>\n<p>Das eigentliche Interessante an der Meldung ist m.E. nach der Trends, dass sich Google immer verst&auml;rkter und organisierter in den Offline-Medien bet&auml;tigt. Auch Projekte wie Google <a href=\"http:\/\/www.googlewatchblog.de\/2008\/07\/02\/streetview-in-frankreich-ist-da\/\" target=\"_blank\">Street View<\/a>, von denen man aktuell auch gelesen hat, dass es in Deutschland in den Startl&ouml;chern steht oder die Google B&uuml;chersuche &#8211; sind nur ein paar Beispiele f&uuml;r Googles Engagement eine Verbindung zwischen der Offline-Welt und Online-Welt herzustellen.<\/p>\n<p>Ich bin der Meinung, dass Google bald in der Lage <strong>off-line-Kampagnen<\/strong> aus den klassichen Medien so zu bewerten, dass die gewonnen Ergebnisse aktiv <strong>in die Ergebnisse<\/strong> der Google Suche <strong>mit einfliessen<\/strong> werden. Beispiele daf&uuml;r k&ouml;nnten sein:<\/p>\n<ul>\n<li>Wie oft wurde ein Werbeplakat gesichtet?<\/li>\n<li>Wie oft lief ein Spot im TV?<\/li>\n<li>Wurden beim Scannen der Zeitschriften &#8211; Werbeanzeigen entdeckt, wenn ja von wem?<\/li>\n<li>Wie oft wurde ein Brand im Radio \/ TV genannt? (Stichwort: spactor.com)<\/li>\n<\/ul>\n<p>Das heisst, wenn ein neuer Brand versucht in den Markt zu dr&auml;ngen und diese Aktion mit einer klassichen Media-Kampagne gekoppelt ist kann das <strong>Auswirkungen auf das Ranking <\/strong>haben und f&auml;llt damit in den Bereich <strong>SEO<\/strong>. Was meint Ihr dazu, ist das zuuuu weit entfernt oder ein kann das ein durchaus realistischer Denkansatz sein?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Google engagiert sich seit geraumer Zeit auch in der Durchf&uuml;hrung von klassischen Media-Kampagnen. Dabei werden Kan&auml;le wie TV, Radio und klassische Printmedien ins Boot genommen. Jetzt hat sich diese noch recht neue Abteilung dazu entschlossen einen offiziellen Blog zu starten. &hellip; <a href=\"https:\/\/www.uwe-tippmann.de\/blog\/2008\/07\/02\/google-offline-geht-online\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1001002,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/www.uwe-tippmann.de\/blog\/wp-json\/wp\/v2\/posts\/336"}],"collection":[{"href":"https:\/\/www.uwe-tippmann.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uwe-tippmann.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uwe-tippmann.de\/blog\/wp-json\/wp\/v2\/users\/1001002"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uwe-tippmann.de\/blog\/wp-json\/wp\/v2\/comments?post=336"}],"version-history":[{"count":0,"href":"https:\/\/www.uwe-tippmann.de\/blog\/wp-json\/wp\/v2\/posts\/336\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.uwe-tippmann.de\/blog\/wp-json\/wp\/v2\/media?parent=336"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uwe-tippmann.de\/blog\/wp-json\/wp\/v2\/categories?post=336"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uwe-tippmann.de\/blog\/wp-json\/wp\/v2\/tags?post=336"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}